{"id":9654,"date":"2026-07-01T17:18:36","date_gmt":"2026-07-01T15:18:36","guid":{"rendered":"https:\/\/www.fergo.eu\/produkt\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/"},"modified":"2026-07-01T17:18:36","modified_gmt":"2026-07-01T15:18:36","slug":"controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3","status":"publish","type":"produkt","link":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/","title":{"rendered":"Contr\u00f4leur de d\u00e9bit \u00e0 3 voies de Flowserve Atomac type ASG3"},"content":{"rendered":"<h2 style=\"text-align: center;\">Flowserve Atomac Hublot 3 voies<\/h2>\n<p class=\"bodytext\">Le hublot FLOWSERVE ATOMAC ASG3 \u00e0 3 voies permet un contr\u00f4le visuel clair des deux c\u00f4t\u00e9s ; rev\u00eatements PFA hautement r\u00e9sistants \u00e0 la corrosion de toutes les pi\u00e8ces internes ; du verre borosilicat\u00e9 conforme \u00e0 la norme DIN 7080 est utilis\u00e9 pour offrir une r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es, aux tensions m\u00e9caniques et \u00e0 la corrosion. Un mat\u00e9riau de rev\u00eatement conducteur en PFA est \u00e9galement disponible en option. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flowserve Atomac Hublot 3 voies Le hublot FLOWSERVE ATOMAC ASG3 \u00e0 3 voies permet un contr\u00f4le visuel clair des deux c\u00f4t\u00e9s ; rev\u00eatements PFA hautement r\u00e9sistants \u00e0 la corrosion de toutes les pi\u00e8ces internes ; du verre borosilicat\u00e9 conforme \u00e0 la norme DIN 7080 est utilis\u00e9 pour offrir une r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es, aux tensions [&hellip;]<\/p>\n","protected":false},"featured_media":9655,"template":"","meta":{"_acf_changed":false,"_acf":"","footnotes":""},"produktgruppe":[155,151],"class_list":["post-9654","produkt","type-produkt","status-publish","has-post-thumbnail","hentry","produktgruppe-controleurs-de-circulation","produktgruppe-vanne-revetue-pfa"],"acf":{"produkt_beschreibung":"<h2 style=\"text-align: center;\">Flowserve Atomac Hublot 3 voies<\/h2>\n<p class=\"bodytext\">Le hublot FLOWSERVE ATOMAC ASG3 \u00e0 3 voies permet un contr\u00f4le visuel clair des deux c\u00f4t\u00e9s ; rev\u00eatements PFA hautement r\u00e9sistants \u00e0 la corrosion de toutes les pi\u00e8ces internes ; du verre borosilicat\u00e9 conforme \u00e0 la norme DIN 7080 est utilis\u00e9 pour offrir une r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es, aux tensions m\u00e9caniques et \u00e0 la corrosion. Un mat\u00e9riau de rev\u00eatement conducteur en PFA est \u00e9galement disponible en option. <\/p>","product_short_desc":"Indicateur de circulation \u00e0 3 voies avec rev\u00eatement PFA","shop_link":"","technische_daten_tabellen_repeater":[{"tabellen_label":"Sp\u00e9cifications techniques","technische_daten_repeater":[{"column_left":"Nom du produit","column_right":"Contr\u00f4leur de d\u00e9bit<br\/>","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"diam\u00e8tres nominaux","column_right":"DN25 - DN100, 1\", 2\", 3\", 4\"","product_fact_display":"top","product_fact_order":1,"shorten":false},{"column_left":"Raccord \u00e0 bride","column_right":"PN10, ANSI 150, PN16","product_fact_display":"top","product_fact_order":2,"shorten":false},{"column_left":"Longueur hors tout","column_right":"DIN EN 558 s\u00e9rie 1","product_fact_display":"top","product_fact_order":3,"shorten":false},{"column_left":"Mat\u00e9riau du bo\u00eetier","column_right":"GGG40+PFA, GGG40+FEP","product_fact_display":"top","product_fact_order":4,"shorten":false},{"column_left":"Niveau de pression","column_right":"PN16","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Rev\u00eatement","column_right":"PFA, FEP","product_fact_display":"top","product_fact_order":5,"shorten":false},{"column_left":"Raccordement","column_right":"Bride","product_fact_display":"none","product_fact_order":"","shorten":false}]}],"produkt_downloads":"<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2021\/01\/ASG3_ger.pdf\">Download \"Schauglas ASG3\" deutsch<\/a>\n\n<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2021\/01\/ASG3_eng.pdf\">Download \"Schauglas ASG3\" englisch<\/a>","datenblaetter_repeater":[{"datenblatt":5692,"download_titel":"T\u00e9l\u00e9charger \u00ab Indicateur de circulation ASG3 \u00bb en allemand"},{"datenblatt":5919,"download_titel":"T\u00e9l\u00e9charger \u00ab Indicateur de circulation ASG3 \u00bb en anglais"}],"variations_repeater":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flowserve Atomac Hublot 3 voies ASG3 rev\u00eatu PFA<\/title>\n<meta name=\"description\" content=\"Flowserve Atomac hublot 3 voies ASG3, rev\u00eatu PFA, DIN DN 25-DN 100, PN16. Large s\u00e9lection disponible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flowserve Atomac Hublot 3 voies ASG3 rev\u00eatu PFA\" \/>\n<meta property=\"og:description\" content=\"Flowserve Atomac hublot 3 voies ASG3, rev\u00eatu PFA, DIN DN 25-DN 100, PN16. Large s\u00e9lection disponible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/\" \/>\n<meta property=\"og:site_name\" content=\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/\",\"name\":\"Flowserve Atomac Hublot 3 voies ASG3 rev\u00eatu PFA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/asg3.png\",\"datePublished\":\"2026-07-01T15:18:36+00:00\",\"description\":\"Flowserve Atomac hublot 3 voies ASG3, rev\u00eatu PFA, DIN DN 25-DN 100, PN16. Large s\u00e9lection disponible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/asg3.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/asg3.png\",\"width\":1417,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contr\u00f4leur de d\u00e9bit \u00e0 3 voies de Flowserve Atomac type ASG3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/\",\"name\":\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\",\"description\":\"Un partenaire comp\u00e9tent et fiable dans le domaine des syst\u00e8mes de commande.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#organization\",\"name\":\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"width\":1000,\"height\":328,\"caption\":\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flowserve Atomac Hublot 3 voies ASG3 rev\u00eatu PFA","description":"Flowserve Atomac hublot 3 voies ASG3, rev\u00eatu PFA, DIN DN 25-DN 100, PN16. Large s\u00e9lection disponible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/","og_locale":"fr_FR","og_type":"article","og_title":"Flowserve Atomac Hublot 3 voies ASG3 rev\u00eatu PFA","og_description":"Flowserve Atomac hublot 3 voies ASG3, rev\u00eatu PFA, DIN DN 25-DN 100, PN16. Large s\u00e9lection disponible.","og_url":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/","og_site_name":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo","og_image":[{"width":1417,"height":1417,"url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg3.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/","url":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/","name":"Flowserve Atomac Hublot 3 voies ASG3 rev\u00eatu PFA","isPartOf":{"@id":"https:\/\/www.fergo.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/#primaryimage"},"image":{"@id":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg3.png","datePublished":"2026-07-01T15:18:36+00:00","description":"Flowserve Atomac hublot 3 voies ASG3, rev\u00eatu PFA, DIN DN 25-DN 100, PN16. Large s\u00e9lection disponible.","breadcrumb":{"@id":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/#primaryimage","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg3.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg3.png","width":1417,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/www.fergo.eu\/fr\/produit\/controleur-de-debit-a-3-voies-de-flowserve-atomac-type-asg3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.fergo.eu\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Contr\u00f4leur de d\u00e9bit \u00e0 3 voies de Flowserve Atomac type ASG3"}]},{"@type":"WebSite","@id":"https:\/\/www.fergo.eu\/fr\/#website","url":"https:\/\/www.fergo.eu\/fr\/","name":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo","description":"Un partenaire comp\u00e9tent et fiable dans le domaine des syst\u00e8mes de commande.","publisher":{"@id":"https:\/\/www.fergo.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fergo.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fergo.eu\/fr\/#organization","name":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo","url":"https:\/\/www.fergo.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fergo.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","width":1000,"height":328,"caption":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo"},"image":{"@id":"https:\/\/www.fergo.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produkt\/9654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":0,"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produkt\/9654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/media\/9655"}],"wp:attachment":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/media?parent=9654"}],"wp:term":[{"taxonomy":"produktgruppe","embeddable":true,"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produktgruppe?post=9654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}