{"id":9678,"date":"2026-07-01T17:18:30","date_gmt":"2026-07-01T15:18:30","guid":{"rendered":"https:\/\/www.fergo.eu\/produkt\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/"},"modified":"2026-07-01T17:18:30","modified_gmt":"2026-07-01T15:18:30","slug":"vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e","status":"publish","type":"produkt","link":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/","title":{"rendered":"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E"},"content":{"rendered":"<h2 style=\"text-align: center;\">Vanne boisseau conique Durco T4E<\/h2>\n<p>Les robinets \u00e0 boisseau conique de la s\u00e9rie FLOWSERVE DURCO T4E ont \u00e9t\u00e9 con\u00e7us et d\u00e9velopp\u00e9s avec une technologie de pointe et conviennent donc parfaitement \u00e0 une utilisation dans l\u2019industrie chimique de transformation. Les robinets \u00e0 boisseau conique sont disponibles dans les classes ASME 150 et 300 ainsi que dans la classe DIN EN PN16 et sont con\u00e7us pour une temp\u00e9rature maximale de 204 \u00b0C. Les robinets \u00e0 boisseau conique DURCO T4E de FLOWSERVE offrent une r\u00e9sistance maximale \u00e0 la corrosion et l\u2019\u00e9limination de la contamination du produit \u00e0 un co\u00fbt raisonnable. Le rev\u00eatement de bo\u00eetier en PFA est solidement ancr\u00e9 dans le bo\u00eetier au moyen de rainures en T usin\u00e9es et moul\u00e9es, et garantit une forte adh\u00e9rence sur l\u2019ensemble de la plage d\u2019utilisation. Les robinets \u00e0 boisseau conique de la s\u00e9rie T4E conviennent donc bien aux conditions de service et de vide extr\u00eames. Une grande surface d\u2019\u00e9tanch\u00e9it\u00e9 garantit une \u00e9tanch\u00e9it\u00e9 parfaite. Une membrane d\u2019\u00e9tanch\u00e9it\u00e9 secondaire statique-dynamique emp\u00eache les fuites au niveau de la tige du robinet \u00e0 boisseau conique. Les si\u00e8ges de vanne ne sont jamais remplac\u00e9s ; gr\u00e2ce \u00e0 un r\u00e9glage rapide et simple dans le syst\u00e8me de tuyauterie, la vanne est r\u00e9ajust\u00e9e.       <\/p>\n<h4>Robinet \u00e0 boisseau T4E2 rev\u00eatu PFA, PN16 (N\u00b0 d&rsquo;art. : 120-1200-xx)<\/h4>\n<ul>\n<li>DN15, DN20, DN25, DN40, DN50, DN80, DN100, DN125, DN150<\/li>\n<li>Passage r\u00e9duit<\/li>\n<li>Raccord \u00e0 bride selon DIN EN 1092-2, PN16<\/li>\n<li>Longueur hors tout : EN 558-1, s\u00e9rie 1<\/li>\n<li>Bo\u00eetier : Fonte \u00e0 graphite sph\u00e9ro\u00efdal EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n<li>Poussin : fonte ductile EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n<li>Couvercle : fonte ductile EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n<li>Rev\u00eatement : PFA<\/li>\n<li>Visserie : A2-70 &#8211; ISO3506 Gr. A2 Cl.70 <\/li>\n<li>Actionnement : Manuel<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Vanne boisseau conique Durco T4E Les robinets \u00e0 boisseau conique de la s\u00e9rie FLOWSERVE DURCO T4E ont \u00e9t\u00e9 con\u00e7us et d\u00e9velopp\u00e9s avec une technologie de pointe et conviennent donc parfaitement \u00e0 une utilisation dans l\u2019industrie chimique de transformation. Les robinets \u00e0 boisseau conique sont disponibles dans les classes ASME 150 et 300 ainsi que dans [&hellip;]<\/p>\n","protected":false},"featured_media":9679,"template":"","meta":{"_acf_changed":false,"_acf":"","footnotes":""},"produktgruppe":[153,151],"class_list":["post-9678","produkt","type-produkt","status-publish","has-post-thumbnail","hentry","produktgruppe-vanne-a-boisseau-conique","produktgruppe-vanne-revetue-pfa"],"acf":{"produkt_beschreibung":"<h2 style=\"text-align: center;\">Vanne boisseau conique Durco T4E<\/h2>\nLes robinets \u00e0 boisseau conique de la s\u00e9rie FLOWSERVE DURCO T4E ont \u00e9t\u00e9 con\u00e7us et d\u00e9velopp\u00e9s avec une technologie de pointe et conviennent donc parfaitement \u00e0 une utilisation dans l\u2019industrie chimique de transformation. Les robinets \u00e0 boisseau conique sont disponibles dans les classes ASME 150 et 300 ainsi que dans la classe DIN EN PN16 et sont con\u00e7us pour une temp\u00e9rature maximale de 204 \u00b0C. Les robinets \u00e0 boisseau conique DURCO T4E de FLOWSERVE offrent une r\u00e9sistance maximale \u00e0 la corrosion et l\u2019\u00e9limination de la contamination du produit \u00e0 un co\u00fbt raisonnable. Le rev\u00eatement de bo\u00eetier en PFA est solidement ancr\u00e9 dans le bo\u00eetier au moyen de rainures en T usin\u00e9es et moul\u00e9es, et garantit une forte adh\u00e9rence sur l\u2019ensemble de la plage d\u2019utilisation. Les robinets \u00e0 boisseau conique de la s\u00e9rie T4E conviennent donc bien aux conditions de service et de vide extr\u00eames. Une grande surface d\u2019\u00e9tanch\u00e9it\u00e9 garantit une \u00e9tanch\u00e9it\u00e9 parfaite. Une membrane d\u2019\u00e9tanch\u00e9it\u00e9 secondaire statique-dynamique emp\u00eache les fuites au niveau de la tige du robinet \u00e0 boisseau conique. Les si\u00e8ges de vanne ne sont jamais remplac\u00e9s ; gr\u00e2ce \u00e0 un r\u00e9glage rapide et simple dans le syst\u00e8me de tuyauterie, la vanne est r\u00e9ajust\u00e9e.       \n<h4>Robinet \u00e0 boisseau T4E2 rev\u00eatu PFA, PN16 (N\u00b0 d'art. : 120-1200-xx)<\/h4>\n<ul>\n \t<li>DN15, DN20, DN25, DN40, DN50, DN80, DN100, DN125, DN150<\/li>\n \t<li>Passage r\u00e9duit<\/li>\n \t<li>Raccord \u00e0 bride selon DIN EN 1092-2, PN16<\/li>\n \t<li>Longueur hors tout : EN 558-1, s\u00e9rie 1<\/li>\n \t<li>Bo\u00eetier : Fonte \u00e0 graphite sph\u00e9ro\u00efdal EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n \t<li>Poussin : fonte ductile EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n \t<li>Couvercle : fonte ductile EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n \t<li>Rev\u00eatement : PFA<\/li>\n \t<li>Visserie : A2-70 - ISO3506 Gr. A2 Cl.70 <\/li>\n \t<li>Actionnement : Manuel<\/li>\n<\/ul>","product_short_desc":"Vanne boisseau conique rev\u00eatu PFA DIN EN PN16","shop_link":"https:\/\/fergo.shop\/Flowserve-PFA-Ausgekleidete-Armaturen","technische_daten_tabellen_repeater":[{"tabellen_label":"Sp\u00e9cifications techniques","technische_daten_repeater":[{"column_left":"Nom du produit","column_right":"Vanne boisseau conique","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"diam\u00e8tres nominaux","column_right":"DN15 - DN150","product_fact_display":"top","product_fact_order":1,"shorten":false},{"column_left":"Raccord \u00e0 bride","column_right":"PN10, PN16","product_fact_display":"top","product_fact_order":2,"shorten":false},{"column_left":"Raccordement","column_right":"Bride","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Longueur hors tout","column_right":"DIN EN 558 s\u00e9rie 1","product_fact_display":"top","product_fact_order":3,"shorten":false},{"column_left":"Mat\u00e9riau du bo\u00eetier","column_right":"GGG40+PFA","product_fact_display":"top","product_fact_order":4,"shorten":false},{"column_left":"Niveau de pression","column_right":"PN16","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Membrane","column_right":"PFA","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Rev\u00eatement","column_right":"PFA","product_fact_display":"top","product_fact_order":5,"shorten":false},{"column_left":"Actionnements","column_right":"\u00e9lectrique, pneumatique double effet, pneumatique simple effet, levier \u00e0 main, bride de montage (ISO 5211), engrenage avec roue \u00e0 main","product_fact_display":"none","product_fact_order":"","shorten":false}]}],"produkt_downloads":"<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2024\/07\/T4E-Flowserve-Fergo-Kuekenhahn-PFA-ausgekleidet.pdf\" target=\"_blank\" rel=\"noopener\">Download \"K\u00fckenhahn T4E2\" deutsch<\/a>\n\n<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2024\/07\/Flowserve-T4E-plug-valves-PFA-lined-valves-Fergo_eng.pdf\" target=\"_blank\" rel=\"noopener\">Download \"K\u00fckenhahn T4E2\" englisch<\/a>","datenblaetter_repeater":[{"datenblatt":5659,"download_titel":"T\u00e9l\u00e9charger \u00ab Robinet \u00e0 boisseau conique T4E2 \u00bb (allemand)"},{"datenblatt":5840,"download_titel":"T\u00e9l\u00e9charger \u00ab Robinet \u00e0 boisseau conique T4E2 \u00bb (anglais)"}],"variations_repeater":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E<\/title>\n<meta name=\"description\" content=\"Vanne bosiseau conique rev\u00eatu PFA , Flowserve Durco T4E, DIN EN PN16, disponible en stock de DN15 \u00e0 DN150. Large stock de produits Flowserve.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E\" \/>\n<meta property=\"og:description\" content=\"Vanne bosiseau conique rev\u00eatu PFA , Flowserve Durco T4E, DIN EN PN16, disponible en stock de DN15 \u00e0 DN150. Large stock de produits Flowserve.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/\" \/>\n<meta property=\"og:site_name\" content=\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1587\" \/>\n\t<meta property=\"og:image:height\" content=\"1587\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/\",\"name\":\"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/t4e2.png\",\"datePublished\":\"2026-07-01T15:18:30+00:00\",\"description\":\"Vanne bosiseau conique rev\u00eatu PFA , Flowserve Durco T4E, DIN EN PN16, disponible en stock de DN15 \u00e0 DN150. Large stock de produits Flowserve.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/t4e2.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/t4e2.png\",\"width\":1587,\"height\":1587},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/produit\\\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/\",\"name\":\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\",\"description\":\"Un partenaire comp\u00e9tent et fiable dans le domaine des syst\u00e8mes de commande.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#organization\",\"name\":\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"width\":1000,\"height\":328,\"caption\":\"Robinetterie industrielle et appareils de commande haut de gamme | Fergo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E","description":"Vanne bosiseau conique rev\u00eatu PFA , Flowserve Durco T4E, DIN EN PN16, disponible en stock de DN15 \u00e0 DN150. Large stock de produits Flowserve.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/","og_locale":"fr_FR","og_type":"article","og_title":"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E","og_description":"Vanne bosiseau conique rev\u00eatu PFA , Flowserve Durco T4E, DIN EN PN16, disponible en stock de DN15 \u00e0 DN150. Large stock de produits Flowserve.","og_url":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/","og_site_name":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo","og_image":[{"width":1587,"height":1587,"url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/","url":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/","name":"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E","isPartOf":{"@id":"https:\/\/www.fergo.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/#primaryimage"},"image":{"@id":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e2.png","datePublished":"2026-07-01T15:18:30+00:00","description":"Vanne bosiseau conique rev\u00eatu PFA , Flowserve Durco T4E, DIN EN PN16, disponible en stock de DN15 \u00e0 DN150. Large stock de produits Flowserve.","breadcrumb":{"@id":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/#primaryimage","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e2.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e2.png","width":1587,"height":1587},{"@type":"BreadcrumbList","@id":"https:\/\/www.fergo.eu\/fr\/produit\/vanne-bosiseau-conique-revetu-pfa-flowserve-durco-t4e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.fergo.eu\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Vanne bosiseau conique rev\u00eatu PFA, Flowserve Durco T4E"}]},{"@type":"WebSite","@id":"https:\/\/www.fergo.eu\/fr\/#website","url":"https:\/\/www.fergo.eu\/fr\/","name":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo","description":"Un partenaire comp\u00e9tent et fiable dans le domaine des syst\u00e8mes de commande.","publisher":{"@id":"https:\/\/www.fergo.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fergo.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fergo.eu\/fr\/#organization","name":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo","url":"https:\/\/www.fergo.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fergo.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","width":1000,"height":328,"caption":"Robinetterie industrielle et appareils de commande haut de gamme | Fergo"},"image":{"@id":"https:\/\/www.fergo.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produkt\/9678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":0,"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produkt\/9678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/media\/9679"}],"wp:attachment":[{"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/media?parent=9678"}],"wp:term":[{"taxonomy":"produktgruppe","embeddable":true,"href":"https:\/\/www.fergo.eu\/fr\/wp-json\/wp\/v2\/produktgruppe?post=9678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}