{"id":9622,"date":"2026-07-01T17:18:36","date_gmt":"2026-07-01T15:18:36","guid":{"rendered":"https:\/\/www.fergo.eu\/produkt\/akh8\/"},"modified":"2026-07-01T17:18:36","modified_gmt":"2026-07-01T15:18:36","slug":"akh8","status":"publish","type":"produkt","link":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/","title":{"rendered":"AKH8"},"content":{"rendered":"<p>Rispetto alla serie esistente di valvole a sfera flottanti, l&#8217;ATOMAC AKH8 \u00e8 una valvola con un&#8217;unit\u00e0 monoblocco sfera-albero di manovra. Il collegamento rigido dei due elementi favorisce l&#8217;uso di fluidi tenaci, altamente viscosi e appiccicosi, specialmente con elevati cicli di commutazione, poich\u00e9 impedisce l&#8217;usura del perno di trascinamento nella fessura della sfera. <\/p>\n<p>L&#8217;eccellente costruzione della tenuta statica e dinamica della flangia del corpo del FLOWSERVE ATOMAC AKH2.2 con la connessione metallo su metallo \u00e8 stata implementata anche in questa nuova valvola a sfera monoblocco. Ci\u00f2 impedisce che le forze di flessione della tubazione e le sollecitazioni termiche alternate influiscano negativamente sulla coppia. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rispetto alla serie esistente di valvole a sfera flottanti, l&#8217;ATOMAC AKH8 \u00e8 una valvola con un&#8217;unit\u00e0 monoblocco sfera-albero di manovra. Il collegamento rigido dei due elementi favorisce l&#8217;uso di fluidi tenaci, altamente viscosi e appiccicosi, specialmente con elevati cicli di commutazione, poich\u00e9 impedisce l&#8217;usura del perno di trascinamento nella fessura della sfera. L&#8217;eccellente costruzione della [&hellip;]<\/p>\n","protected":false},"featured_media":9623,"template":"","meta":{"_acf_changed":false,"_acf":"","footnotes":""},"produktgruppe":[166],"class_list":["post-9622","produkt","type-produkt","status-publish","has-post-thumbnail","hentry","produktgruppe-valvola-a-sfera-revista-pfa"],"acf":{"produkt_beschreibung":"Rispetto alla serie esistente di valvole a sfera flottanti, l'ATOMAC AKH8 \u00e8 una valvola con un'unit\u00e0 monoblocco sfera-albero di manovra. Il collegamento rigido dei due elementi favorisce l'uso di fluidi tenaci, altamente viscosi e appiccicosi, specialmente con elevati cicli di commutazione, poich\u00e9 impedisce l'usura del perno di trascinamento nella fessura della sfera. \n\nL'eccellente costruzione della tenuta statica e dinamica della flangia del corpo del FLOWSERVE ATOMAC AKH2.2 con la connessione metallo su metallo \u00e8 stata implementata anche in questa nuova valvola a sfera monoblocco. Ci\u00f2 impedisce che le forze di flessione della tubazione e le sollecitazioni termiche alternate influiscano negativamente sulla coppia. ","product_short_desc":"Valvola a sfera monoblocco rivestita in PFA","shop_link":"","technische_daten_tabellen_repeater":[{"tabellen_label":"Specifiche tecniche","technische_daten_repeater":[{"column_left":"Denominazione del prodotto","column_right":"Valvola a sfera","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Diametri nominali","column_right":"DN15 - DN100","product_fact_display":"top","product_fact_order":1,"shorten":false},{"column_left":"Attacco flangiato","column_right":"PN10, PN16","product_fact_display":"top","product_fact_order":2,"shorten":false},{"column_left":"Collegamento","column_right":"Flange","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"lunghezza","column_right":"DIN EN 558-1","product_fact_display":"top","product_fact_order":3,"shorten":false},{"column_left":"Materiale dell'involucro","column_right":"GGG40+PFA, GGG40+FEP","product_fact_display":"top","product_fact_order":4,"shorten":false},{"column_left":"Scatola per l'imbottitura","column_right":"PTFE, PTFE+grafite","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Livello di pressione","column_right":"PN16","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Materiale della palla","column_right":"Rivestimento in PFA, rivestimento in FEP","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Sede della palla","column_right":"PTFE","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Fodera","column_right":"PFA, FEP","product_fact_display":"top","product_fact_order":5,"shorten":false},{"column_left":"azionamenti","column_right":"Motore elettrico, Pneumatico a doppio effetto, Pneumatico a semplice effetto, Leva manuale, Flangia di montaggio (ISO 5211), Scatola ingranaggi con volantino","product_fact_display":"none","product_fact_order":"","shorten":false}]}],"produkt_downloads":"<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2021\/01\/AKH8_ger.pdf\">Download \"Valvola a sfera AKH8\" tedesco<\/a>\n\n<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2021\/01\/AKH8_eng.pdf\">Download \"Valvola a sfera AKH8\" inglese<\/a>\n\n<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2021\/01\/AKH8A_ger.pdf\">Download \"Valvola a sfera AKH8A\" tedesco<\/a>\n\n<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2021\/01\/AKH8A_eng.pdf\">Download \"Valvola a sfera AKH8A\" inglese<\/a>","datenblaetter_repeater":[{"datenblatt":5683,"download_titel":"Download \"Valvola a sfera AKH8\" tedesco"},{"datenblatt":5908,"download_titel":"Download \"Valvola a sfera AKH8\" inglese"},{"datenblatt":5909,"download_titel":"Download \"Valvola a sfera AKH8A\" tedesco"},{"datenblatt":5910,"download_titel":"Download \"Valvola a sfera AKH8A\" inglese"}],"variations_repeater":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AKH8 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo<\/title>\n<meta name=\"description\" content=\"La valvola a sfera flottante AKH8 di ATOMAC offre alte prestazioni, ideale per fluidi viscosi ed elevati cicli di commutazione, con una lunga durata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AKH8 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\" \/>\n<meta property=\"og:description\" content=\"La valvola a sfera flottante AKH8 di ATOMAC offre alte prestazioni, ideale per fluidi viscosi ed elevati cicli di commutazione, con una lunga durata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/\" \/>\n<meta property=\"og:site_name\" content=\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/akh8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1984\" \/>\n\t<meta property=\"og:image:height\" content=\"1984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/\",\"name\":\"AKH8 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/akh8.png\",\"datePublished\":\"2026-07-01T15:18:36+00:00\",\"description\":\"La valvola a sfera flottante AKH8 di ATOMAC offre alte prestazioni, ideale per fluidi viscosi ed elevati cicli di commutazione, con una lunga durata.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/akh8.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/akh8.png\",\"width\":1984,\"height\":1984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/akh8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/valvole-e-controlli-industriali\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AKH8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/\",\"name\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"description\":\"Un partner competente e affidabile nel settore della tecnologia di controllo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#organization\",\"name\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"width\":1000,\"height\":328,\"caption\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AKH8 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","description":"La valvola a sfera flottante AKH8 di ATOMAC offre alte prestazioni, ideale per fluidi viscosi ed elevati cicli di commutazione, con una lunga durata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/","og_locale":"it_IT","og_type":"article","og_title":"AKH8 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","og_description":"La valvola a sfera flottante AKH8 di ATOMAC offre alte prestazioni, ideale per fluidi viscosi ed elevati cicli di commutazione, con una lunga durata.","og_url":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/","og_site_name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","og_image":[{"width":1984,"height":1984,"url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/akh8.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/","url":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/","name":"AKH8 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","isPartOf":{"@id":"https:\/\/www.fergo.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/#primaryimage"},"image":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/akh8.png","datePublished":"2026-07-01T15:18:36+00:00","description":"La valvola a sfera flottante AKH8 di ATOMAC offre alte prestazioni, ideale per fluidi viscosi ed elevati cicli di commutazione, con una lunga durata.","breadcrumb":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/#primaryimage","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/akh8.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/akh8.png","width":1984,"height":1984},{"@type":"BreadcrumbList","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/akh8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.fergo.eu\/it\/valvole-e-controlli-industriali\/"},{"@type":"ListItem","position":2,"name":"AKH8"}]},{"@type":"WebSite","@id":"https:\/\/www.fergo.eu\/it\/#website","url":"https:\/\/www.fergo.eu\/it\/","name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","description":"Un partner competente e affidabile nel settore della tecnologia di controllo.","publisher":{"@id":"https:\/\/www.fergo.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fergo.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fergo.eu\/it\/#organization","name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","url":"https:\/\/www.fergo.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fergo.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","width":1000,"height":328,"caption":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo"},"image":{"@id":"https:\/\/www.fergo.eu\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt\/9622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":0,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt\/9622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/media\/9623"}],"wp:attachment":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/media?parent=9622"}],"wp:term":[{"taxonomy":"produktgruppe","embeddable":true,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produktgruppe?post=9622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}