{"id":9652,"date":"2026-07-01T17:18:36","date_gmt":"2026-07-01T15:18:36","guid":{"rendered":"https:\/\/www.fergo.eu\/produkt\/indicatore-visivo-flowserve-atomac-asg4\/"},"modified":"2026-07-01T17:18:36","modified_gmt":"2026-07-01T15:18:36","slug":"indicatore-visivo-flowserve-atomac-asg4","status":"publish","type":"produkt","link":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/","title":{"rendered":"Indicatore visivo FLOWSERVE ATOMAC ASG4"},"content":{"rendered":"<p class=\"bodytext\">L&#8217;indicatore visivo FLOWSERVE ATOMAC ASG4 permette un chiaro controllo visivo da entrambi i lati; rivestimento altamente resistente alla corrosione di tutte le parti interne; viene utilizzato vetro borosilicato a norma DIN 7080 per offrire resistenza alle alte temperature, alle sollecitazioni meccaniche e alla corrosione. Disponibile opzionalmente anche con materiale di rivestimento PFA conduttivo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;indicatore visivo FLOWSERVE ATOMAC ASG4 permette un chiaro controllo visivo da entrambi i lati; rivestimento altamente resistente alla corrosione di tutte le parti interne; viene utilizzato vetro borosilicato a norma DIN 7080 per offrire resistenza alle alte temperature, alle sollecitazioni meccaniche e alla corrosione. Disponibile opzionalmente anche con materiale di rivestimento PFA conduttivo.<\/p>\n","protected":false},"featured_media":9653,"template":"","meta":{"_acf_changed":false,"_acf":"","footnotes":""},"produktgruppe":[170,166],"class_list":["post-9652","produkt","type-produkt","status-publish","has-post-thumbnail","hentry","produktgruppe-controllore-di-flusso","produktgruppe-valvola-a-sfera-revista-pfa"],"acf":{"produkt_beschreibung":"<p class=\"bodytext\">L'indicatore visivo FLOWSERVE ATOMAC ASG4 permette un chiaro controllo visivo da entrambi i lati; rivestimento altamente resistente alla corrosione di tutte le parti interne; viene utilizzato vetro borosilicato a norma DIN 7080 per offrire resistenza alle alte temperature, alle sollecitazioni meccaniche e alla corrosione. Disponibile opzionalmente anche con materiale di rivestimento PFA conduttivo. <\/p>","product_short_desc":"Indicatore visivo a 4 vie con rivestimento in PFA","shop_link":"","technische_daten_tabellen_repeater":[{"tabellen_label":"Specifiche tecniche","technische_daten_repeater":[{"column_left":"Denominazione del prodotto","column_right":"Vetro spia","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Diametri nominali","column_right":"DN25, DN50, DN80, 1\", 2\", 3\".","product_fact_display":"top","product_fact_order":1,"shorten":false},{"column_left":"Attacco flangiato","column_right":"PN10, ANSI 150, PN16","product_fact_display":"top","product_fact_order":2,"shorten":false},{"column_left":"lunghezza","column_right":"DIN EN 558 Serie 1","product_fact_display":"top","product_fact_order":3,"shorten":false},{"column_left":"Materiale dell'involucro","column_right":"GGG40+PFA, GGG40+FEP","product_fact_display":"top","product_fact_order":4,"shorten":false},{"column_left":"Livello di pressione","column_right":"PN16","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Fodera","column_right":"PFA, FEP","product_fact_display":"top","product_fact_order":5,"shorten":false},{"column_left":"Collegamento","column_right":"Flange","product_fact_display":"none","product_fact_order":"","shorten":false}]}],"produkt_downloads":"<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2019\/01\/ASG4_ger.pdf\">Download \"Indicatore visivo ASG4\" in tedesco<\/a>","datenblaetter_repeater":[{"datenblatt":5693,"download_titel":"Download \"Indicatore visivo ASG4\" in tedesco"}],"variations_repeater":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indicatore visivo FLOWSERVE ATOMAC ASG4 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo<\/title>\n<meta name=\"description\" content=\"L&#039;indicatore visivo a 4 vie ATOMAC ASG4 offre un controllo visivo chiaro con rivestimento in PFA e vetro borosilicato per un&#039;elevata resistenza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indicatore visivo FLOWSERVE ATOMAC ASG4 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\" \/>\n<meta property=\"og:description\" content=\"L&#039;indicatore visivo a 4 vie ATOMAC ASG4 offre un controllo visivo chiaro con rivestimento in PFA e vetro borosilicato per un&#039;elevata resistenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/\" \/>\n<meta property=\"og:site_name\" content=\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1247\" \/>\n\t<meta property=\"og:image:height\" content=\"1247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/\",\"name\":\"Indicatore visivo FLOWSERVE ATOMAC ASG4 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/asg4.png\",\"datePublished\":\"2026-07-01T15:18:36+00:00\",\"description\":\"L'indicatore visivo a 4 vie ATOMAC ASG4 offre un controllo visivo chiaro con rivestimento in PFA e vetro borosilicato per un'elevata resistenza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/asg4.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/asg4.png\",\"width\":1247,\"height\":1247},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/indicatore-visivo-flowserve-atomac-asg4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/valvole-e-controlli-industriali\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indicatore visivo FLOWSERVE ATOMAC ASG4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/\",\"name\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"description\":\"Un partner competente e affidabile nel settore della tecnologia di controllo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#organization\",\"name\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"width\":1000,\"height\":328,\"caption\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indicatore visivo FLOWSERVE ATOMAC ASG4 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","description":"L'indicatore visivo a 4 vie ATOMAC ASG4 offre un controllo visivo chiaro con rivestimento in PFA e vetro borosilicato per un'elevata resistenza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/","og_locale":"it_IT","og_type":"article","og_title":"Indicatore visivo FLOWSERVE ATOMAC ASG4 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","og_description":"L'indicatore visivo a 4 vie ATOMAC ASG4 offre un controllo visivo chiaro con rivestimento in PFA e vetro borosilicato per un'elevata resistenza.","og_url":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/","og_site_name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","og_image":[{"width":1247,"height":1247,"url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg4.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/","url":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/","name":"Indicatore visivo FLOWSERVE ATOMAC ASG4 - Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","isPartOf":{"@id":"https:\/\/www.fergo.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/#primaryimage"},"image":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg4.png","datePublished":"2026-07-01T15:18:36+00:00","description":"L'indicatore visivo a 4 vie ATOMAC ASG4 offre un controllo visivo chiaro con rivestimento in PFA e vetro borosilicato per un'elevata resistenza.","breadcrumb":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/#primaryimage","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg4.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/asg4.png","width":1247,"height":1247},{"@type":"BreadcrumbList","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/indicatore-visivo-flowserve-atomac-asg4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.fergo.eu\/it\/valvole-e-controlli-industriali\/"},{"@type":"ListItem","position":2,"name":"Indicatore visivo FLOWSERVE ATOMAC ASG4"}]},{"@type":"WebSite","@id":"https:\/\/www.fergo.eu\/it\/#website","url":"https:\/\/www.fergo.eu\/it\/","name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","description":"Un partner competente e affidabile nel settore della tecnologia di controllo.","publisher":{"@id":"https:\/\/www.fergo.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fergo.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fergo.eu\/it\/#organization","name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","url":"https:\/\/www.fergo.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fergo.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","width":1000,"height":328,"caption":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo"},"image":{"@id":"https:\/\/www.fergo.eu\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt\/9652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":0,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt\/9652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/media\/9653"}],"wp:attachment":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/media?parent=9652"}],"wp:term":[{"taxonomy":"produktgruppe","embeddable":true,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produktgruppe?post=9652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}