{"id":9674,"date":"2026-07-01T17:18:30","date_gmt":"2026-07-01T15:18:30","guid":{"rendered":"https:\/\/www.fergo.eu\/produkt\/valvola-a-maschio-flowserve-durco-t4e3\/"},"modified":"2026-07-01T17:18:30","modified_gmt":"2026-07-01T15:18:30","slug":"valvola-a-maschio-flowserve-durco-t4e3","status":"publish","type":"produkt","link":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/","title":{"rendered":"Valvola a maschio Flowserve Durco T4E3"},"content":{"rendered":"<h2 style=\"text-align: center;\">Valvole a maschio Durco<\/h2>\n<p>Le valvole a maschio della serie FLOWSERVE DURCO T4E sono progettate e sviluppate con tecnologia all&#8217;avanguardia, rendendole ideali per l&#8217;uso nell&#8217;industria chimica di processo. Le valvole a maschio sono disponibili nelle classi ASME 150 e 300, nonch\u00e9 nella classe DIN EN PN16, e sono progettate per una temperatura massima di 204\u00b0C. Le valvole a maschio DURCO T4E offrono la massima resistenza alla corrosione e l&#8217;eliminazione della contaminazione del prodotto con un costo ragionevole. Il rivestimento dell&#8217;alloggiamento in PFA \u00e8 saldamente ancorato nell&#8217;alloggiamento tramite scanalature a T lavorate e fuse meccanicamente, garantendo una forte adesione su tutto il campo di applicazione. Pertanto, le valvole a maschio della serie T4E di FLOWSERVE sono ben adatte per condizioni operative e di vuoto estreme. Un&#8217;ampia superficie di tenuta garantisce una chiusura a tenuta stagna. Una membrana di tenuta secondaria statico-dinamica previene le perdite dallo stelo della valvola a maschio. Le sedi delle valvole non vengono mai sostituite; l&#8217;armatura viene riregolata mediante una regolazione rapida e semplice nel sistema di tubazioni.       <\/p>\n<h4>Valvola a maschio rivestita in PFA T4E3, 300lbs (Art.-Nr.: 120-1220-xx)<\/h4>\n<ul>\n<li>1\/2&#8243;, 3\/4&#8243;, 1&#8243;, 1 1\/2&#8243;, 2&#8243;, 3&#8243;, 4&#8243;, 5&#8243;, 6&#8243;, 8&#8243;, 10&#8243;, 12&#8243;<\/li>\n<li>Passaggio ridotto<\/li>\n<li>Attacco flangiato secondo ASME B16.5 (300lbs)<\/li>\n<li>lunghezza secondo ASME B16.10<\/li>\n<li>Alloggiamento: Ghisa sferoidale EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n<li>Pollo: Ghisa sferoidale EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n<li>Coperchio: Ghisa sferoidale EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n<li>Fodera: PFA<\/li>\n<li>Attacco a vite: ASTM A193 misura B7<\/li>\n<li>Azionamento: manuale<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Valvole a maschio Durco Le valvole a maschio della serie FLOWSERVE DURCO T4E sono progettate e sviluppate con tecnologia all&#8217;avanguardia, rendendole ideali per l&#8217;uso nell&#8217;industria chimica di processo. Le valvole a maschio sono disponibili nelle classi ASME 150 e 300, nonch\u00e9 nella classe DIN EN PN16, e sono progettate per una temperatura massima di 204\u00b0C. [&hellip;]<\/p>\n","protected":false},"featured_media":9675,"template":"","meta":{"_acf_changed":false,"_acf":"","footnotes":""},"produktgruppe":[168,166],"class_list":["post-9674","produkt","type-produkt","status-publish","has-post-thumbnail","hentry","produktgruppe-valvole-a-sfera-conico","produktgruppe-valvola-a-sfera-revista-pfa"],"acf":{"produkt_beschreibung":"<h2 style=\"text-align: center;\">Valvole a maschio Durco<\/h2>\nLe valvole a maschio della serie FLOWSERVE DURCO T4E sono progettate e sviluppate con tecnologia all'avanguardia, rendendole ideali per l'uso nell'industria chimica di processo. Le valvole a maschio sono disponibili nelle classi ASME 150 e 300, nonch\u00e9 nella classe DIN EN PN16, e sono progettate per una temperatura massima di 204\u00b0C. Le valvole a maschio DURCO T4E offrono la massima resistenza alla corrosione e l'eliminazione della contaminazione del prodotto con un costo ragionevole. Il rivestimento dell'alloggiamento in PFA \u00e8 saldamente ancorato nell'alloggiamento tramite scanalature a T lavorate e fuse meccanicamente, garantendo una forte adesione su tutto il campo di applicazione. Pertanto, le valvole a maschio della serie T4E di FLOWSERVE sono ben adatte per condizioni operative e di vuoto estreme. Un'ampia superficie di tenuta garantisce una chiusura a tenuta stagna. Una membrana di tenuta secondaria statico-dinamica previene le perdite dallo stelo della valvola a maschio. Le sedi delle valvole non vengono mai sostituite; l'armatura viene riregolata mediante una regolazione rapida e semplice nel sistema di tubazioni.       \n<h4>Valvola a maschio rivestita in PFA T4E3, 300lbs (Art.-Nr.: 120-1220-xx)<\/h4>\n<ul>\n \t<li>1\/2\", 3\/4\", 1\", 1 1\/2\", 2\", 3\", 4\", 5\", 6\", 8\", 10\", 12\"<\/li>\n \t<li>Passaggio ridotto<\/li>\n \t<li>Attacco flangiato secondo ASME B16.5 (300lbs)<\/li>\n \t<li>lunghezza secondo ASME B16.10<\/li>\n \t<li>Alloggiamento: Ghisa sferoidale EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n \t<li>Pollo: Ghisa sferoidale EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n \t<li>Coperchio: Ghisa sferoidale EN-JS1049 \/ A395 Gr. 60-40-18<\/li>\n \t<li>Fodera: PFA<\/li>\n \t<li>Attacco a vite: ASTM A193 misura B7<\/li>\n \t<li>Azionamento: manuale<\/li>\n<\/ul>","product_short_desc":"Valvola a maschio rivestita in PFA classe ASME 300","shop_link":"https:\/\/fergo.shop\/PFA-Ausgekleidete-Armaturen\/PFA-ausgekleideter-Kuekenhahn\/","technische_daten_tabellen_repeater":[{"tabellen_label":"Specifiche tecniche","technische_daten_repeater":[{"column_left":"Denominazione del prodotto","column_right":"Cazzo di pulcino","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Diametri nominali","column_right":"1\/2\" - 6\"","product_fact_display":"top","product_fact_order":1,"shorten":false},{"column_left":"Attacco flangiato","column_right":"ANSI 300","product_fact_display":"top","product_fact_order":2,"shorten":false},{"column_left":"Collegamento","column_right":"Flange","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"lunghezza","column_right":"ANSI B 16.10","product_fact_display":"top","product_fact_order":3,"shorten":false},{"column_left":"Materiale dell'involucro","column_right":"Acciaio+PFA","product_fact_display":"top","product_fact_order":4,"shorten":false},{"column_left":"Livello di pressione","column_right":"Classe 300","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Membrana","column_right":"PFA","product_fact_display":"none","product_fact_order":"","shorten":false},{"column_left":"Fodera","column_right":"PFA","product_fact_display":"top","product_fact_order":5,"shorten":false},{"column_left":"azionamenti","column_right":"Motore elettrico, Pneumatico a doppio effetto, Pneumatico a semplice effetto, Leva manuale, Flangia di montaggio (ISO 5211), Scatola ingranaggi con volantino","product_fact_display":"none","product_fact_order":"","shorten":false}]}],"produkt_downloads":"<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2024\/07\/T4E-Flowserve-Fergo-Kuekenhahn-PFA-ausgekleidet.pdf\" target=\"_blank\" rel=\"noopener\">Download \"Valvola a maschio T4E3\" tedesco<\/a>\n\n<a href=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2024\/07\/Flowserve-T4E-plug-valves-PFA-lined-valves-Fergo_eng.pdf\" target=\"_blank\" rel=\"noopener\">Download \"Valvola a maschio T4E3\" inglese<\/a>","datenblaetter_repeater":[{"datenblatt":5659,"download_titel":"Download \"Valvola a maschio T4E3\" tedesco"},{"datenblatt":5840,"download_titel":"Download \"Valvola a maschio T4E3\" inglese"}],"variations_repeater":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valvole a maschio Flowserve Durco T4E3 con rivestimento in PFA<\/title>\n<meta name=\"description\" content=\"Valvola a maschio Flowserve Durco rivestita in PFA ASME 300. Disponibile da 1\/2 pollice a 12 pollici. Prodotti Flowserve in grandi quantit\u00e0 a magazzino.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valvole a maschio Flowserve Durco T4E3 con rivestimento in PFA\" \/>\n<meta property=\"og:description\" content=\"Valvola a maschio Flowserve Durco rivestita in PFA ASME 300. Disponibile da 1\/2 pollice a 12 pollici. Prodotti Flowserve in grandi quantit\u00e0 a magazzino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/\" \/>\n<meta property=\"og:site_name\" content=\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"1134\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/\",\"name\":\"Valvole a maschio Flowserve Durco T4E3 con rivestimento in PFA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/t4e3.png\",\"datePublished\":\"2026-07-01T15:18:30+00:00\",\"description\":\"Valvola a maschio Flowserve Durco rivestita in PFA ASME 300. Disponibile da 1\\\/2 pollice a 12 pollici. Prodotti Flowserve in grandi quantit\u00e0 a magazzino.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/t4e3.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/t4e3.png\",\"width\":1134,\"height\":1134,\"caption\":\"|\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/prodotto\\\/valvola-a-maschio-flowserve-durco-t4e3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/valvole-e-controlli-industriali\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valvola a maschio Flowserve Durco T4E3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/\",\"name\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"description\":\"Un partner competente e affidabile nel settore della tecnologia di controllo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#organization\",\"name\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fergo.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/fergo-gmbh-logo.png\",\"width\":1000,\"height\":328,\"caption\":\"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fergo.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valvole a maschio Flowserve Durco T4E3 con rivestimento in PFA","description":"Valvola a maschio Flowserve Durco rivestita in PFA ASME 300. Disponibile da 1\/2 pollice a 12 pollici. Prodotti Flowserve in grandi quantit\u00e0 a magazzino.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/","og_locale":"it_IT","og_type":"article","og_title":"Valvole a maschio Flowserve Durco T4E3 con rivestimento in PFA","og_description":"Valvola a maschio Flowserve Durco rivestita in PFA ASME 300. Disponibile da 1\/2 pollice a 12 pollici. Prodotti Flowserve in grandi quantit\u00e0 a magazzino.","og_url":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/","og_site_name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","og_image":[{"width":1134,"height":1134,"url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/","url":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/","name":"Valvole a maschio Flowserve Durco T4E3 con rivestimento in PFA","isPartOf":{"@id":"https:\/\/www.fergo.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/#primaryimage"},"image":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e3.png","datePublished":"2026-07-01T15:18:30+00:00","description":"Valvola a maschio Flowserve Durco rivestita in PFA ASME 300. Disponibile da 1\/2 pollice a 12 pollici. Prodotti Flowserve in grandi quantit\u00e0 a magazzino.","breadcrumb":{"@id":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/#primaryimage","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e3.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/06\/t4e3.png","width":1134,"height":1134,"caption":"|"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fergo.eu\/it\/prodotto\/valvola-a-maschio-flowserve-durco-t4e3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.fergo.eu\/it\/valvole-e-controlli-industriali\/"},{"@type":"ListItem","position":2,"name":"Valvola a maschio Flowserve Durco T4E3"}]},{"@type":"WebSite","@id":"https:\/\/www.fergo.eu\/it\/#website","url":"https:\/\/www.fergo.eu\/it\/","name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","description":"Un partner competente e affidabile nel settore della tecnologia di controllo.","publisher":{"@id":"https:\/\/www.fergo.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fergo.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fergo.eu\/it\/#organization","name":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo","url":"https:\/\/www.fergo.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fergo.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","contentUrl":"https:\/\/www.fergo.eu\/wp-content\/uploads\/2026\/05\/fergo-gmbh-logo.png","width":1000,"height":328,"caption":"Rubinetteria industriale e dispositivi di controllo di alta qualit\u00e0 | Fergo"},"image":{"@id":"https:\/\/www.fergo.eu\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt\/9674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":0,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produkt\/9674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/media\/9675"}],"wp:attachment":[{"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/media?parent=9674"}],"wp:term":[{"taxonomy":"produktgruppe","embeddable":true,"href":"https:\/\/www.fergo.eu\/it\/wp-json\/wp\/v2\/produktgruppe?post=9674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}